{"id":19799,"date":"2023-02-09T13:53:57","date_gmt":"2023-02-09T05:53:57","guid":{"rendered":"https:\/\/www.ftsafe.com\/payment\/?page_id=19799"},"modified":"2023-03-25T16:41:22","modified_gmt":"2023-03-25T08:41:22","slug":"f210-3","status":"publish","type":"page","link":"https:\/\/www.ftsafe.com\/payment\/ru\/f210-3\/","title":{"rendered":"F210"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"19799\" class=\"elementor elementor-19799\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3c4c42 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b3c4c42\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da4cdbd\" data-id=\"da4cdbd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43836e5 elementor-widget elementor-widget-image\" data-id=\"43836e5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"810\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Russian-F210.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Russian-F210.jpg 1920w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Russian-F210-300x127.jpg 300w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Russian-F210-1024x432.jpg 1024w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Russian-F210-768x324.jpg 768w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Russian-F210-1536x648.jpg 1536w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Russian-F210-24x10.jpg 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Russian-F210-36x15.jpg 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Russian-F210-48x20.jpg 48w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-121f9a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"121f9a3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5909945\" data-id=\"5909945\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75d02a7 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"75d02a7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u041c\u043d\u043e\u0433\u043e\u043a\u0430\u043d\u0430\u043b\u044c\u043d\u044b\u0439 \u043f\u043b\u0430\u0442\u0435\u0436<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-58c3bee elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"58c3bee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-107ee07 animated-slow elementor-invisible\" data-id=\"107ee07\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40fbe01 elementor-cta--skin-cover elementor-cta--valign-middle elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"40fbe01\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/img01-3.png);\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"87\" height=\"75\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/nfc-icon.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/nfc-icon.png 87w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/nfc-icon-24x21.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/nfc-icon-36x31.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/nfc-icon-48x41.png 48w\" sizes=\"(max-width: 87px) 100vw, 87px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\tNFC<br\/>\nPayment\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0678e2a animated-slow elementor-invisible\" data-id=\"0678e2a\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b0f92b elementor-cta--skin-cover elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"1b0f92b\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/img02-3.png);\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"104\" height=\"78\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/bank.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/bank.png 104w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/bank-24x18.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/bank-36x27.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/bank-48x36.png 48w\" sizes=\"(max-width: 104px) 100vw, 104px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\tStripe Card<br\/>\nPayment\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f9725fc animated-slow elementor-invisible\" data-id=\"f9725fc\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47fe394 elementor-cta--skin-cover elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"47fe394\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/img03-3.png);\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"75\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/ICcardPayment-icon-1.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/ICcardPayment-icon-1.png 100w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/ICcardPayment-icon-1-24x18.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/ICcardPayment-icon-1-36x27.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/ICcardPayment-icon-1-48x36.png 48w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\tIC card<br\/>\nPayment\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-700faf9 animated-slow elementor-invisible\" data-id=\"700faf9\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:400}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b756270 elementor-cta--skin-cover elementor-cta--valign-middle elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"b756270\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/img04-3.png);\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"83\" height=\"83\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/erweima.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/erweima.png 83w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/erweima-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/erweima-36x36.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/05\/erweima-48x48.png 48w\" sizes=\"(max-width: 83px) 100vw, 83px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\tQR Code <br\/>Payment\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fa4358 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4fa4358\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d36923b\" data-id=\"d36923b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-09de052 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"09de052\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-44e03b3\" data-id=\"44e03b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c5e146 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7c5e146\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:5}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0420\u0430\u0441\u0448\u0438\u0440\u0435\u043d\u043d\u044b\u0435 \u0432\u043e\u0437\u043c\u043e\u0436\u043d\u043e\u0441\u0442\u0438 \u043f\u043e\u0434\u043a\u043b\u044e\u0447\u0435\u043d\u0438\u044f, \u0432\u044b\u0441\u043e\u043a\u0430\u044f \u043f\u0440\u043e\u0438\u0437\u0432\u043e\u0434\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38daca0 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"38daca0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:10}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u041e\u0441\u043d\u043e\u0432\u0430\u043d \u043d\u0430 \u041e\u0421 Android 10, \u0432\u044b\u0441\u043e\u043a\u043e\u043f\u0440\u043e\u0438\u0437\u0432\u043e\u0434\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u043c \u0447\u0435\u0442\u044b\u0440\u0435\u0445\u044a\u044f\u0434\u0435\u0440\u043d\u043e\u043c \u043f\u0440\u043e\u0446\u0435\u0441\u0441\u043e\u0440\u0435 \u0438 \u0441\u0442\u0430\u0431\u0438\u043b\u044c\u043d\u043e\u0439 \u0441\u0435\u0442\u0438, F210 \u043e\u0431\u0435\u0441\u043f\u0435\u0447\u0438\u0432\u0430\u0435\u0442 \u0431\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u044b\u0435 \u0438 \u0431\u044b\u0441\u0442\u0440\u044b\u0435 \u043f\u043b\u0430\u0442\u0435\u0436\u0438 \u0434\u043b\u044f \u0442\u043e\u0440\u0433\u043e\u0432\u0446\u0435\u0432<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9eb9b1 animated-slow homepage-icon elementor-invisible elementor-widget elementor-widget-image-gallery\" data-id=\"c9eb9b1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:15}\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-19799 gallery-columns-5 gallery-size-menu-48x48'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"44\" height=\"48\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/Android-1-44x48.png\" class=\"attachment-menu-48x48 size-menu-48x48\" alt=\"\" aria-describedby=\"gallery-1-16356\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/Android-1-44x48.png 44w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/Android-1-22x24.png 22w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/Android-1-33x36.png 33w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/Android-1.png 61w\" sizes=\"(max-width: 44px) 100vw, 44px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-16356'>\n\t\t\t\tAndroid 12\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"44\" height=\"48\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/CPU-2-44x48.png\" class=\"attachment-menu-48x48 size-menu-48x48\" alt=\"\" aria-describedby=\"gallery-1-16358\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/CPU-2-44x48.png 44w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/CPU-2-22x24.png 22w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/CPU-2-33x36.png 33w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/CPU-2.png 61w\" sizes=\"(max-width: 44px) 100vw, 44px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-16358'>\n\t\t\t\tQuad-Core 1.4G, A53\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/4G-1-48x48.png\" class=\"attachment-menu-48x48 size-menu-48x48\" alt=\"\" aria-describedby=\"gallery-1-16355\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/4G-1-48x48.png 48w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/4G-1-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/4G-1-36x36.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/4G-1.png 65w\" sizes=\"(max-width: 48px) 100vw, 48px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-16355'>\n\t\t\t\t4G\/3G\/2G \n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/WIFI-48x48.png\" class=\"attachment-menu-48x48 size-menu-48x48\" alt=\"\" aria-describedby=\"gallery-1-16359\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/WIFI-48x48.png 48w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/WIFI-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/WIFI-36x36.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/WIFI.png 65w\" sizes=\"(max-width: 48px) 100vw, 48px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-16359'>\n\t\t\t\t WiFi\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/Bluetooth-1-48x48.png\" class=\"attachment-menu-48x48 size-menu-48x48\" alt=\"\" aria-describedby=\"gallery-1-16357\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/Bluetooth-1-48x48.png 48w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/Bluetooth-1-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/Bluetooth-1-36x36.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/06\/Bluetooth-1.png 65w\" sizes=\"(max-width: 48px) 100vw, 48px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-16357'>\n\t\t\t\t Bluetooth\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fc098d4\" data-id=\"fc098d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0bb5245 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0bb5245\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f36e22\" data-id=\"7f36e22\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4e408a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e408a7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b65de50\" data-id=\"b65de50\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c8fc1a6\" data-id=\"c8fc1a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17401cd animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"17401cd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:5}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u041a\u043e\u043c\u043f\u0430\u043a\u0442\u043d\u044b\u0439 \u0438 \u0441\u0442\u0438\u043b\u044c\u043d\u044b\u0439 \u0432\u043d\u0435\u0448\u043d\u0438\u0439 \u0432\u0438\u0434<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6913a56 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6913a56\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:10}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">5-\u0434\u044e\u0439\u043c\u043e\u0432\u044b\u0439 \u0441\u0435\u043d\u0441\u043e\u0440\u043d\u044b\u0439 \u044d\u043a\u0440\u0430\u043d HD \u043b\u0443\u0447\u0448\u0435 \u043b\u043e\u0436\u0438\u0442\u0441\u044f \u0432 \u0440\u0443\u043a\u0443 \u0438 \u043e\u0431\u0435\u0441\u043f\u0435\u0447\u0438\u0432\u0430\u0435\u0442 \u0432\u0435\u043b\u0438\u043a\u043e\u043b\u0435\u043f\u043d\u044b\u0435 \u043e\u0449\u0443\u0449\u0435\u043d\u0438\u044f \u043e\u0442 \u043f\u0440\u043e\u0441\u043c\u043e\u0442\u0440\u0430 \u0438 \u043f\u0440\u0438\u043a\u043e\u0441\u043d\u043e\u0432\u0435\u043d\u0438\u044f<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf32409 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"cf32409\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ff7582\" data-id=\"0ff7582\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a1f289 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6a1f289\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0421\u0432\u0435\u0440\u0445\u0434\u043b\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0441\u0440\u043e\u043a \u0441\u043b\u0443\u0436\u0431\u044b \u0431\u0430\u0442\u0430\u0440\u0435\u0438<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd8f81b animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"bd8f81b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0411\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u044f \u0431\u0430\u0442\u0430\u0440\u0435\u0439\u043a\u0435 \u0431\u043e\u043b\u044c\u0448\u043e\u0439 \u0435\u043c\u043a\u043e\u0441\u0442\u044c\u044e 5000 \u043c\u0410\u0447 FEITIAN F210 \u043f\u043e\u0437\u0432\u043e\u043b\u044f\u0435\u0442 \u043f\u0440\u043e\u0434\u0430\u0432\u0446\u0430\u043c \u0441\u043e\u0441\u0440\u0435\u0434\u043e\u0442\u043e\u0447\u0438\u0442\u044c\u0441\u044f \u043d\u0430 \u0431\u0438\u0437\u043d\u0435\u0441\u0435 \u0432 \u0442\u0435\u0447\u0435\u043d\u0438\u0435 \u0432\u0441\u0435\u0433\u043e \u0434\u043d\u044f<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dc7ad0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3dc7ad0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c2c226\" data-id=\"7c2c226\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6d80c05 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d80c05\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-87a2612\" data-id=\"87a2612\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56b92d7 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"56b92d7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:5}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0412\u044b\u0441\u043e\u043a\u043e\u0441\u043a\u043e\u0440\u043e\u0441\u0442\u043d\u043e\u0439 \u043f\u0440\u0438\u043d\u0442\u0435\u0440, \u043f\u043b\u0430\u0432\u043d\u0430\u044f \u043f\u0435\u0447\u0430\u0442\u044c<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b26940c animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b26940c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:10}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0422\u0435\u0440\u043c\u043e\u043f\u0440\u0438\u043d\u0442\u0435\u0440 FEITIAN F210 \u043e\u0431\u043b\u0430\u0434\u0430\u0435\u0442 \u0431\u043e\u043b\u0435\u0435 \u0432\u044b\u0441\u043e\u043a\u043e\u0439 \u0441\u043a\u043e\u0440\u043e\u0441\u0442\u044c\u044e, \u0447\u0442\u043e \u043e\u0431\u0435\u0441\u043f\u0435\u0447\u0438\u0432\u0430\u0435\u0442 \u0431\u044b\u0441\u0442\u0440\u0443\u044e \u0438 \u043f\u043b\u0430\u0432\u043d\u0443\u044e \u043f\u0435\u0447\u0430\u0442\u044c \u0447\u0435\u043a\u043e\u0432 \u0434\u043b\u044f \u043a\u043b\u0438\u0435\u043d\u0442\u043e\u0432<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e689940 animated-slow elementor-invisible elementor-widget elementor-widget-image-gallery\" data-id=\"e689940\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:15}\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-2 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-2 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-2' class='gallery galleryid-19799 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"88\" height=\"85\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Printing-Paper.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-19801\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Printing-Paper.png 88w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Printing-Paper-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Printing-Paper-36x36.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Printing-Paper-48x46.png 48w\" sizes=\"(max-width: 88px) 100vw, 88px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-2-19801'>\n\t\t\t\t\u0420\u0430\u0437\u043c\u0435\u0440 \u0440\u0443\u043b\u043e\u043d\u0430: 58 * 40 \u043c\u043c\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"88\" height=\"85\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/speed.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-19802\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/speed.png 88w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/speed-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/speed-36x36.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/speed-48x46.png 48w\" sizes=\"(max-width: 88px) 100vw, 88px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-2-19802'>\n\t\t\t\t\u0421\u043a\u043e\u0440\u043e\u0441\u0442\u044c \u043f\u0435\u0447\u0430\u0442\u0438: 75 \u043c\u043c \/ \u0441 \n\t\t\t\t<\/dd><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e35df3b\" data-id=\"e35df3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ab2a16 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0ab2a16\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56b7a7d\" data-id=\"56b7a7d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4786303 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4786303\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u0421\u0446\u0435\u043d\u0430\u0440\u0438\u0438 \u043f\u0440\u0438\u043c\u0435\u043d\u0435\u043d\u0438\u044f<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d8fe9d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8fe9d9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-bdf3604\" data-id=\"bdf3604\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76563c2 elementor-cta--skin-cover elementor-cta--valign-middle animated-slow elementor-animated-content elementor-invisible elementor-widget elementor-widget-call-to-action\" data-id=\"76563c2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_delay&quot;:5}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Retail-2.png);\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--fade-in\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"188\" height=\"188\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Retail-.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Retail-.png 188w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Retail--150x150.png 150w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Retail--24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Retail--36x36.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Retail--48x48.png 48w\" sizes=\"(max-width: 188px) 100vw, 188px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-d39fe43\" data-id=\"d39fe43\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b1aa93 elementor-cta--skin-cover elementor-cta--valign-middle animated-slow elementor-animated-content elementor-invisible elementor-widget elementor-widget-call-to-action\" data-id=\"3b1aa93\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_delay&quot;:10}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Supermarket.png);\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--fade-in\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"188\" height=\"188\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Supermarket-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Supermarket-1.png 188w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Supermarket-1-150x150.png 150w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Supermarket-1-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Supermarket-1-36x36.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Supermarket-1-48x48.png 48w\" sizes=\"(max-width: 188px) 100vw, 188px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-d968026\" data-id=\"d968026\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a903569 elementor-cta--skin-cover elementor-cta--valign-middle animated-slow elementor-animated-content elementor-invisible elementor-widget elementor-widget-call-to-action\" data-id=\"a903569\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_delay&quot;:15}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Restaurant.png);\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--fade-in\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"188\" height=\"188\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Restaurant-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Restaurant-1.png 188w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Restaurant-1-150x150.png 150w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Restaurant-1-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Restaurant-1-36x36.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Restaurant-1-48x48.png 48w\" sizes=\"(max-width: 188px) 100vw, 188px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-c7668b6\" data-id=\"c7668b6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e516e2 elementor-cta--skin-cover elementor-cta--valign-middle animated-slow elementor-animated-content elementor-invisible elementor-widget elementor-widget-call-to-action\" data-id=\"7e516e2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_delay&quot;:20}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Hotel.png);\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--fade-in\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"188\" height=\"188\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Hotel-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Hotel-1.png 188w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Hotel-1-150x150.png 150w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Hotel-1-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Hotel-1-36x36.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Hotel-1-48x48.png 48w\" sizes=\"(max-width: 188px) 100vw, 188px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-56d785d\" data-id=\"56d785d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea805d8 elementor-cta--skin-cover elementor-cta--valign-middle animated-slow elementor-animated-content elementor-invisible elementor-widget elementor-widget-call-to-action\" data-id=\"ea805d8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_delay&quot;:25}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Parking-Lot.png);\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--fade-in\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"188\" height=\"188\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Parking-Lot-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Parking-Lot-1.png 188w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Parking-Lot-1-150x150.png 150w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Parking-Lot-1-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Parking-Lot-1-36x36.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Parking-Lot-1-48x48.png 48w\" sizes=\"(max-width: 188px) 100vw, 188px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-08cb816\" data-id=\"08cb816\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cce54a5 elementor-cta--skin-cover elementor-cta--valign-middle animated-slow elementor-animated-content elementor-invisible elementor-widget elementor-widget-call-to-action\" data-id=\"cce54a5\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_delay&quot;:30}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Gas-Station.png);\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--fade-in\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"188\" height=\"188\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Gas-Station-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Gas-Station-1.png 188w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Gas-Station-1-150x150.png 150w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Gas-Station-1-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Gas-Station-1-36x36.png 36w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2023\/02\/Gas-Station-1-48x48.png 48w\" sizes=\"(max-width: 188px) 100vw, 188px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed4caac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed4caac\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f6e244\" data-id=\"7f6e244\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e3d6dd animated-slow elementor-invisible elementor-widget elementor-widget-html\" data-id=\"7e3d6dd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:0}\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t \n<div class=\"payment-type-product\">\n    <span class=\"payment-product-item-name\">F210<\/span>\n    <span class=\"payment-product-item-desc\">\u0421\u043f\u0435\u0446\u0438\u0444\u0438\u043a\u0430\u0446\u0438\u044f<\/span>\n    \n<\/div>\n\n \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa200ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa200ce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-77229cf animated-slow elementor-invisible\" data-id=\"77229cf\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:0}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1371559 elementor-position-left animated-slow elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"1371559\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:2000,&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/anzhuo.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/anzhuo.png 60w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/anzhuo-21x24.png 21w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/anzhuo-31x36.png 31w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/anzhuo-41x48.png 41w\" sizes=\"(max-width: 60px) 100vw, 60px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">\u041e\u0421<\/h5><p class=\"elementor-image-box-description\">Android10<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5c30987 animated-slow elementor-invisible\" data-id=\"5c30987\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a91678 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"8a91678\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/CPU-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/CPU-1.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/CPU-1-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/CPU-1-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/CPU-1-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">CPU<\/h5><p class=\"elementor-image-box-description\">Quad-Core 4\u00d71.4G, A53<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-be8fb4d animated-slow elementor-invisible\" data-id=\"be8fb4d\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67514ca elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"67514ca\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/cunchu.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/cunchu.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/cunchu-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/cunchu-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/cunchu-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">\u041f\u0430\u043c\u044f\u0442\u044c<\/h5><p class=\"elementor-image-box-description\">1GB + 8GB<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-9a4ab88 animated-slow elementor-invisible\" data-id=\"9a4ab88\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:900}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-816656f elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"816656f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Display-2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Display-2.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Display-2-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Display-2-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Display-2-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">\u0420\u0430\u0437\u043c\u0435\u0440<\/h5><p class=\"elementor-image-box-description\">197mm (L) \u00d7 82.1mm (W) \u00d7 52.5mm (H)<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e86bb9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e86bb9f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7143541 animated-slow elementor-invisible\" data-id=\"7143541\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:1200}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59dc278 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"59dc278\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/wifi.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/wifi.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/wifi-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/wifi-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/wifi-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Wifi<\/h5><p class=\"elementor-image-box-description\">2.4G, 802.11 b\/g\/n<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f2036db animated-slow elementor-invisible\" data-id=\"f2036db\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:1500}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-364d873 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"364d873\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"47\" height=\"53\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/lanya.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/lanya.png 47w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/lanya-21x24.png 21w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/lanya-32x36.png 32w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/lanya-43x48.png 43w\" sizes=\"(max-width: 47px) 100vw, 47px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Bluetooth<\/h5><p class=\"elementor-image-box-description\">BT2.1+BLE4.2<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-289f03d animated-slow elementor-invisible\" data-id=\"289f03d\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:1800}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db0c0cc elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"db0c0cc\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/GPS.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/GPS.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/GPS-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/GPS-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/GPS-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">GPS<\/h5><p class=\"elementor-image-box-description\">GPS, Beidou<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5255375 animated-slow elementor-invisible\" data-id=\"5255375\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:2100}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b300c2 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"9b300c2\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/camera-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/camera-1.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/camera-1-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/camera-1-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/camera-1-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">\u041a\u0430\u043c\u0435\u0440\u0430<\/h5><p class=\"elementor-image-box-description\">\u0417\u0430\u0434\u043d\u044f\u044f:  8M AF <br\/>\n\u0424\u0440\u043e\u043d\u0442\u0430\u043b\u044c\u043d\u0430\u044f\uff1a2M FF<br\/><\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-05d9e29 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"05d9e29\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8447e0a animated-slow elementor-invisible\" data-id=\"8447e0a\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:2400}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e6be93 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"1e6be93\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/LCM.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/LCM.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/LCM-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/LCM-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/LCM-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">\u0414\u0438\u0441\u043f\u043b\u0435\u0439<\/h5><p class=\"elementor-image-box-description\">5\" (1280 \u00d7 720) ,IPS<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-65d327f animated-slow elementor-invisible\" data-id=\"65d327f\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:2700}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e759e2 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"6e759e2\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/SIM.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/SIM.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/SIM-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/SIM-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/SIM-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">\u0421\u043b\u043e\u0442 \u0434\u043b\u044f \u043a\u0430\u0440\u0442<\/h5><p class=\"elementor-image-box-description\">2x micro SIM +1 PSAM <br\/>1* micro SD  <\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-58dcc6a animated-slow elementor-invisible\" data-id=\"58dcc6a\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:3000}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e4dbf7 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"8e4dbf7\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Battery-2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Battery-2.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Battery-2-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Battery-2-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Battery-2-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">\u0411\u0430\u0442\u0430\u0440\u0435\u0439\u043a\u0430<\/h5><p class=\"elementor-image-box-description\">3.8V, 5000mAh<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f948cc5 animated-slow elementor-invisible\" data-id=\"f948cc5\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:3300}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84ed57e elementor-position-left animated-slow elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"84ed57e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:4800}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Power.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Power.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Power-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Power-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Power-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">\u041c\u043e\u0449\u043d\u043e\u0441\u0442\u044c<\/h5><p class=\"elementor-image-box-description\">\u0412\u0445\u043e\u0434: 100-240V, 50\/60Hz  0.35A<br>\n\u0412\u044b\u0432\u043e\u0434: 5V\/2000mA<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a0d418 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a0d418\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-77f73a6 animated-slow elementor-invisible\" data-id=\"77f73a6\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:3600}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5a9891 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"a5a9891\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Magnetic-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Magnetic-1.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Magnetic-1-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Magnetic-1-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Magnetic-1-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">MSR<\/h5><p class=\"elementor-image-box-description\">ISO\/IEC 7811, ISO\/IEC 7813, 1\/2\/3 \u0434\u043e\u0440\u043e\u0436\u043a\u0438, 2-\u043d\u0430\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u043d\u044b\u0439<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c2f0562 animated-slow elementor-invisible\" data-id=\"c2f0562\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:3900}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c499654 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"c499654\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/IC-Card.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/IC-Card.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/IC-Card-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/IC-Card-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/IC-Card-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">IC<\/h5><p class=\"elementor-image-box-description\">ISO\/IEC 7816, \u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0438\u0435 EMV L1\/L2<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d0c781a animated-slow elementor-invisible\" data-id=\"d0c781a\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:4200}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-571c1a8 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"571c1a8\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Nfc-2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Nfc-2.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Nfc-2-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Nfc-2-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Nfc-2-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">NFC<\/h5><p class=\"elementor-image-box-description\">13.56MHz, ISO\/IEC 14443, Type A&B,  ISO18092,  Felica, Mifare card<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e4a6eac animated-slow elementor-invisible\" data-id=\"e4a6eac\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:4500}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c839b9 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"7c839b9\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/QR-Code.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/QR-Code.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/QR-Code-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/QR-Code-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/QR-Code-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">QR \u041a\u043e\u0434<\/h5><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4184540 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4184540\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-71d94a1\" data-id=\"71d94a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06e12a6 elementor-position-left animated-slow elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"06e12a6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:4800}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/usb-2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/usb-2.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/usb-2-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/usb-2-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/usb-2-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">\u041f\u043e\u0440\u0442<\/h5><p class=\"elementor-image-box-description\">Type C<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-cdf9937\" data-id=\"cdf9937\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3890a3e elementor-position-left animated-slow elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"3890a3e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:4800}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"73\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/10\/\u91cd\u91cf.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/10\/\u91cd\u91cf.png 57w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/10\/\u91cd\u91cf-19x24.png 19w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/10\/\u91cd\u91cf-28x36.png 28w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/10\/\u91cd\u91cf-37x48.png 37w\" sizes=\"(max-width: 57px) 100vw, 57px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">\u0412\u0435\u0441<\/h5><p class=\"elementor-image-box-description\">410\u0433<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-35e0a38\" data-id=\"35e0a38\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-472df09 elementor-position-left animated-slow elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"472df09\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:4800}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Printer-2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Printer-2.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Printer-2-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Printer-2-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/Printer-2-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">\u041f\u0440\u0438\u043d\u0442\u0435\u0440<\/h5><p class=\"elementor-image-box-description\">\u0422\u0435\u0440\u043c\u043e\u043f\u0440\u0438\u043d\u0442\u0435\u0440, \u0431\u0443\u043c\u0430\u0433\u0430: 58*40 \u043c\u043c<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e742932\" data-id=\"e742932\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3c823f elementor-position-left animated-slow elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"f3c823f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:4800}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"70\" src=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/zhengshu-icon.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/zhengshu-icon.png 66w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/zhengshu-icon-24x24.png 24w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/zhengshu-icon-34x36.png 34w, https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2021\/06\/zhengshu-icon-45x48.png 45w\" sizes=\"(max-width: 66px) 100vw, 66px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">\u0421\u0435\u0440\u0442\u0438\u0444\u0438\u043a\u0442\u044b<\/h5><p class=\"elementor-image-box-description\">PCI 6.1, EMV L1&L2, EMV Contactless L1\nPaypass, payWave, AMEX ExpressPay, Discover, Quics, JCB, Pure, TQM\nFCC, CE, RoHS, WEEE<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df6a279 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df6a279\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d23066\" data-id=\"1d23066\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82621c8 elementor-button-success elementor-align-center elementor-widget elementor-widget-button\" data-id=\"82621c8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.ftsafe.com\/payment\/wp-content\/uploads\/2022\/11\/F210_11-2.pdf\" class=\"elementor-button-link elementor-button elementor-size-xs\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-download\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download F210 brochure <\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u041c\u043d\u043e\u0433\u043e\u043a\u0430\u043d\u0430\u043b\u044c\u043d\u044b\u0439 \u043f\u043b\u0430\u0442\u0435\u0436 NFC Payment Stripe Card Payment IC card Payment QR Code Payment \u0420\u0430\u0441\u0448\u0438\u0440\u0435\u043d\u043d\u044b\u0435 \u0432\u043e\u0437\u043c\u043e\u0436\u043d\u043e\u0441\u0442\u0438 \u043f\u043e\u0434\u043a\u043b\u044e\u0447\u0435\u043d\u0438\u044f, \u0432\u044b\u0441\u043e\u043a\u0430\u044f \u043f\u0440\u043e\u0438\u0437\u0432\u043e\u0434\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c \u041e\u0441\u043d\u043e\u0432\u0430\u043d \u043d\u0430 \u041e\u0421 Android 10, \u0432\u044b\u0441\u043e\u043a\u043e\u043f\u0440\u043e\u0438\u0437\u0432\u043e\u0434\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u043c \u0447\u0435\u0442\u044b\u0440\u0435\u0445\u044a\u044f\u0434\u0435\u0440\u043d\u043e\u043c \u043f\u0440\u043e\u0446\u0435\u0441\u0441\u043e\u0440\u0435 \u0438 \u0441\u0442\u0430\u0431\u0438\u043b\u044c\u043d\u043e\u0439 \u0441\u0435\u0442\u0438, F210 \u043e\u0431\u0435\u0441\u043f\u0435\u0447\u0438\u0432\u0430\u0435\u0442 \u0431\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u044b\u0435 \u0438 \u0431\u044b\u0441\u0442\u0440\u044b\u0435 \u043f\u043b\u0430\u0442\u0435\u0436\u0438 \u0434\u043b\u044f \u0442\u043e\u0440\u0433\u043e\u0432\u0446\u0435\u0432 Android 10 Quad-Core 1.4G, A53 4G\/3G\/2G WiFi Bluetooth \u041a\u043e\u043c\u043f\u0430\u043a\u0442\u043d\u044b\u0439 \u0438 \u0441\u0442\u0438\u043b\u044c\u043d\u044b\u0439 \u0432\u043d\u0435\u0448\u043d\u0438\u0439 \u0432\u0438\u0434 5-\u0434\u044e\u0439\u043c\u043e\u0432\u044b\u0439 \u0441\u0435\u043d\u0441\u043e\u0440\u043d\u044b\u0439 \u044d\u043a\u0440\u0430\u043d HD \u043b\u0443\u0447\u0448\u0435 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.ftsafe.com\/payment\/wp-json\/wp\/v2\/pages\/19799"}],"collection":[{"href":"https:\/\/www.ftsafe.com\/payment\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ftsafe.com\/payment\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ftsafe.com\/payment\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ftsafe.com\/payment\/wp-json\/wp\/v2\/comments?post=19799"}],"version-history":[{"count":16,"href":"https:\/\/www.ftsafe.com\/payment\/wp-json\/wp\/v2\/pages\/19799\/revisions"}],"predecessor-version":[{"id":20184,"href":"https:\/\/www.ftsafe.com\/payment\/wp-json\/wp\/v2\/pages\/19799\/revisions\/20184"}],"wp:attachment":[{"href":"https:\/\/www.ftsafe.com\/payment\/wp-json\/wp\/v2\/media?parent=19799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}